{"id":14948,"date":"2018-06-25T14:58:57","date_gmt":"2018-06-25T14:58:57","guid":{"rendered":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web.jpg"},"modified":"2018-06-25T14:58:57","modified_gmt":"2018-06-25T14:58:57","slug":"933-210-45b4_margit_web","status":"inherit","type":"attachment","link":"https:\/\/www.kuldkroon.ee\/en\/933-210-45b4_margit_web\/","title":{"rendered":"933-210-45B4_Margit_web"},"author":53,"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"class_list":["post-14948","attachment","type-attachment","status-inherit","hentry"],"acf":[],"description":{"rendered":"<p class=\"attachment\"><span class=\"fresco\" data-fresco-group=\"\" href='https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web.jpg'><img loading=\"lazy\" decoding=\"async\" width=\"163\" height=\"300\" src=\"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-163x300.jpg\" class=\"attachment-medium size-medium\" alt=\"\" srcset=\"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-163x300.jpg 163w, https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-350x645.jpg 350w, https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-570x1051.jpg 570w, https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-768x1416.jpg 768w, https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-556x1024.jpg 556w, https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-600x1106.jpg 600w, https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web.jpg 868w\" sizes=\"auto, (max-width: 163px) 100vw, 163px\" \/><\/a><\/p>\n"},"caption":{"rendered":""},"alt_text":"","media_type":"image","mime_type":"image\/jpeg","media_details":{"width":868,"height":1600,"file":"2018\/06\/933-210-45B4_Margit_web.jpg","filesize":178311,"sizes":{"woocommerce_thumbnail":{"file":"933-210-45B4_Margit_web-350x645.jpg","width":350,"height":645,"filesize":52039,"uncropped":true,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-350x645.jpg"},"woocommerce_gallery_thumbnail":{"file":"933-210-45B4_Margit_web-100x100.jpg","width":100,"height":100,"filesize":14168,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-100x100.jpg"},"woocommerce_single":{"file":"933-210-45B4_Margit_web-570x1051.jpg","width":570,"height":1051,"filesize":97253,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-570x1051.jpg"},"thumbnail":{"file":"933-210-45B4_Margit_web-150x150.jpg","width":150,"height":150,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-150x150.jpg"},"medium":{"file":"933-210-45B4_Margit_web-163x300.jpg","width":163,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-163x300.jpg"},"medium_large":{"file":"933-210-45B4_Margit_web-768x1416.jpg","width":768,"height":1416,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-768x1416.jpg"},"large":{"file":"933-210-45B4_Margit_web-556x1024.jpg","width":556,"height":1024,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-556x1024.jpg"},"woodstock_product_small_thumbnail":{"file":"933-210-45B4_Margit_web-116x126.jpg","width":116,"height":126,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-116x126.jpg"},"woodstock_shop_single_small_thumbnail":{"file":"933-210-45B4_Margit_web-190x206.jpg","width":190,"height":206,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-190x206.jpg"},"woodstock_blog-isotope":{"file":"933-210-45B4_Margit_web-620x500.jpg","width":620,"height":500,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-620x500.jpg"},"woodstock-widget-image":{"file":"933-210-45B4_Margit_web-94x70.jpg","width":94,"height":70,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-94x70.jpg"},"woodstock-thumb-square":{"file":"933-210-45B4_Margit_web-120x120.jpg","width":120,"height":120,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-120x120.jpg"},"woodstock-thumb-image":{"file":"933-210-45B4_Margit_web-600x450.jpg","width":600,"height":450,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-600x450.jpg"},"woodstock-thumb-image-twocol":{"file":"933-210-45B4_Margit_web-868x675.jpg","width":868,"height":675,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-868x675.jpg"},"woodstock-thumb-image-onecol":{"file":"933-210-45B4_Margit_web-868x1200.jpg","width":868,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-868x1200.jpg"},"woodstock-large-square":{"file":"933-210-45B4_Margit_web-868x1200.jpg","width":868,"height":1200,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-868x1200.jpg"},"woodstock-full-width-image-gallery":{"file":"933-210-45B4_Margit_web-868x720.jpg","width":868,"height":720,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-868x720.jpg"},"shop_catalog":{"file":"933-210-45B4_Margit_web-300x300.jpg","width":300,"height":300,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-300x300.jpg"},"shop_single":{"file":"933-210-45B4_Margit_web-600x1106.jpg","width":600,"height":1106,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-600x1106.jpg"},"shop_thumbnail":{"file":"933-210-45B4_Margit_web-100x100.jpg","width":100,"height":100,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web-100x100.jpg"},"full":{"file":"933-210-45B4_Margit_web.jpg","width":868,"height":1600,"mime_type":"image\/jpeg","source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web.jpg"}},"image_meta":{"aperture":"57","credit":"","camera":"NIKON D7100","caption":"","created_timestamp":"1377436799","copyright":"","focal_length":"105","iso":"200","shutter_speed":"0.004","title":"","orientation":"1","keywords":[]}},"post":null,"source_url":"https:\/\/kuldkroon.ee\/wp-content\/uploads\/2018\/06\/933-210-45B4_Margit_web.jpg","_links":{"self":[{"href":"https:\/\/www.kuldkroon.ee\/en\/wp-json\/wp\/v2\/media\/14948","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.kuldkroon.ee\/en\/wp-json\/wp\/v2\/media"}],"about":[{"href":"https:\/\/www.kuldkroon.ee\/en\/wp-json\/wp\/v2\/types\/attachment"}],"author":[{"embeddable":true,"href":"https:\/\/www.kuldkroon.ee\/en\/wp-json\/wp\/v2\/users\/53"}],"replies":[{"embeddable":true,"href":"https:\/\/www.kuldkroon.ee\/en\/wp-json\/wp\/v2\/comments?post=14948"}]}}